{"id":544,"date":"2024-01-21T22:17:41","date_gmt":"2024-01-21T21:17:41","guid":{"rendered":"https:\/\/perdifly.com\/?p=544"},"modified":"2024-08-01T23:04:20","modified_gmt":"2024-08-01T21:04:20","slug":"tutoriel-la-passe-partout","status":"publish","type":"post","link":"https:\/\/perdifly.com\/index.php\/2024\/01\/21\/tutoriel-la-passe-partout\/","title":{"rendered":"La passe partout"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00ab\u00a0La passe partout\u00a0\u00bb est une \u00e9mergente que l&rsquo;on peut classer dans la cat\u00e9gorie des mouches d&rsquo;ensemble faite de li\u00e8vre et de CDC. Cette \u00e9mergente flotte bas et les fibres de CDC permettent de la mouche de rester dans la pellicule d&rsquo;eau.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tr\u00e8s efficace en p\u00e8che de bordure quand les March Brown sont de sorties (taille H 10-H12) , elle s&rsquo;av\u00e8re aussi prenant quant les truites sont port\u00e9es sur les \u00e9mergente de sedges (taille H14-H16)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Place maintenant \u00e0 la vid\u00e9o de montage<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"nv-iframe-embed\"><iframe loading=\"lazy\" title=\"Tuto mouche Passe Partout\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/rB5w3gacXyE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Bon montage \u00e0 vous. <\/p>\n\n\n\n<div style=\"height:22px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0La passe partout\u00a0\u00bb est une \u00e9mergente que l&rsquo;on peut classer dans la cat\u00e9gorie des mouches d&rsquo;ensemble faite de li\u00e8vre et de CDC. Cette \u00e9mergente flotte bas et les fibres de CDC permettent de la mouche de rester dans la pellicule d&rsquo;eau. Tr\u00e8s efficace en p\u00e8che de bordure quand les March Brown sont de sorties (taille&hellip;&nbsp;<a href=\"https:\/\/perdifly.com\/index.php\/2024\/01\/21\/tutoriel-la-passe-partout\/\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">La passe partout<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":548,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[2],"tags":[8,48],"class_list":["post-544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-flytying","tag-emergente","tag-montage"],"_links":{"self":[{"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/posts\/544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/comments?post=544"}],"version-history":[{"count":5,"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/posts\/544\/revisions"}],"predecessor-version":[{"id":1438,"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/posts\/544\/revisions\/1438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/media\/548"}],"wp:attachment":[{"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/media?parent=544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/categories?post=544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perdifly.com\/index.php\/wp-json\/wp\/v2\/tags?post=544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}